{"id":10059,"date":"2024-08-19T17:24:52","date_gmt":"2024-08-19T17:24:52","guid":{"rendered":"https:\/\/uni-crema.it\/uni-crema\/?p=10059"},"modified":"2024-09-22T09:34:14","modified_gmt":"2024-09-22T09:34:14","slug":"ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna","status":"publish","type":"post","link":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/","title":{"rendered":"Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna"},"content":{"rendered":"<p>I docenti di UNI-Crema propongono una visita a Bologna per visitare la mostra dedicata ad Antonio Ligabue a Palazzo Pallavicini, quindi al santuario e al portico di San Luca.<\/p>\n<h3>Quando<\/h3>\n<p>Sabato 19 ottobre 2024.<\/p>\n<h3>Iscrizioni<\/h3>\n<p>Le adesioni si ricevono fino ad esaurimento posti mediante il versamento della quota di partecipazione presso l\u2019agenzia viaggi GerundoTour (Largo della Pace, 10 \u2013 Porta Nova, telefono <a href=\"tel:+390373259309\">0373 259 309<\/a>).<\/p>\n<h3>Quota di partecipazione<\/h3>\n<p>Euro 88,00 (iscritti UNI-Crema) e euro 90,00 (non iscritti UNI-Crema).<\/p>\n<!-- WP Attachments -->\r\n        <div style=\"width:100%;margin:10px 0 10px 0;\">\r\n            <h3>Allegati<\/h3>\r\n        <ul class=\"post-attachments\"><li class=\"post-attachment mime-application-pdf\"><a href=\"https:\/\/uni-crema.it\/uni-crema\/wp-content\/uploads\/2024\/08\/Bologna-rev1.pdf\">Scarica il programma<\/a> <small>(144 kB)<\/small><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>I docenti di UNI-Crema propongono una visita a Bologna per visitare la mostra dedicata ad Antonio Ligabue a Palazzo Pallavicini, quindi al santuario e al portico di San Luca. Quando Sabato 19 ottobre 2024. Iscrizioni Le adesioni si ricevono fino ad esaurimento posti mediante il versamento della quota di partecipazione presso l\u2019agenzia viaggi GerundoTour (Largo&hellip;&nbsp;<a href=\"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":10061,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":70,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"cybocfi_hide_featured_image":"","footnotes":""},"categories":[23],"tags":[],"post_folder":[],"class_list":["post-10059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna - UNI-Crema<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna - UNI-Crema\" \/>\n<meta property=\"og:description\" content=\"I docenti di UNI-Crema propongono una visita a Bologna per visitare la mostra dedicata ad Antonio Ligabue a Palazzo Pallavicini, quindi al santuario e al portico di San Luca. Quando Sabato 19 ottobre 2024. Iscrizioni Le adesioni si ricevono fino ad esaurimento posti mediante il versamento della quota di partecipazione presso l\u2019agenzia viaggi GerundoTour (Largo&hellip;&nbsp;Leggi tutto &raquo;Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/\" \/>\n<meta property=\"og:site_name\" content=\"UNI-Crema\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-19T17:24:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-22T09:34:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uni-crema.it\/uni-crema\/wp-content\/uploads\/2024\/08\/ligabue-pallavicini-bologna.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"222\" \/>\n\t<meta property=\"og:image:height\" content=\"222\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/2024\\\/08\\\/19\\\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/2024\\\/08\\\/19\\\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/#\\\/schema\\\/person\\\/cfe1a0a64654788fe56bb76b1ff14816\"},\"headline\":\"Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna\",\"datePublished\":\"2024-08-19T17:24:52+00:00\",\"dateModified\":\"2024-09-22T09:34:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/2024\\\/08\\\/19\\\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\\\/\"},\"wordCount\":82,\"publisher\":{\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/2024\\\/08\\\/19\\\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/ligabue-pallavicini-bologna.jpg\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/2024\\\/08\\\/19\\\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\\\/\",\"url\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/2024\\\/08\\\/19\\\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\\\/\",\"name\":\"Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna - UNI-Crema\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/2024\\\/08\\\/19\\\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/2024\\\/08\\\/19\\\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/ligabue-pallavicini-bologna.jpg\",\"datePublished\":\"2024-08-19T17:24:52+00:00\",\"dateModified\":\"2024-09-22T09:34:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/2024\\\/08\\\/19\\\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/2024\\\/08\\\/19\\\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/2024\\\/08\\\/19\\\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/ligabue-pallavicini-bologna.jpg\",\"contentUrl\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/ligabue-pallavicini-bologna.jpg\",\"width\":222,\"height\":222},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/2024\\\/08\\\/19\\\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/#website\",\"url\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/\",\"name\":\"UNI-Crema\",\"description\":\"Libera Universit\u00e0 per l&#039;Et\u00e0 Adulta\",\"publisher\":{\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/#organization\"},\"alternateName\":\"UNI-Crema\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/#organization\",\"name\":\"uni-Crema\",\"alternateName\":\"Libera Universit\u00e0 per l'Et\u00e0 Adulta\",\"url\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/kigo-UNI-Crema.png\",\"contentUrl\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/kigo-UNI-Crema.png\",\"width\":292,\"height\":234,\"caption\":\"uni-Crema\"},\"image\":{\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/#\\\/schema\\\/person\\\/cfe1a0a64654788fe56bb76b1ff14816\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88214e2decd2e7f1897b7efe07c01fd3e24142626dfbca18f4e479a8adbb6540?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88214e2decd2e7f1897b7efe07c01fd3e24142626dfbca18f4e479a8adbb6540?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88214e2decd2e7f1897b7efe07c01fd3e24142626dfbca18f4e479a8adbb6540?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/uni-crema.it\\\/uni-crema\"],\"url\":\"https:\\\/\\\/uni-crema.it\\\/uni-crema\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna - UNI-Crema","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/","og_locale":"it_IT","og_type":"article","og_title":"Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna - UNI-Crema","og_description":"I docenti di UNI-Crema propongono una visita a Bologna per visitare la mostra dedicata ad Antonio Ligabue a Palazzo Pallavicini, quindi al santuario e al portico di San Luca. Quando Sabato 19 ottobre 2024. Iscrizioni Le adesioni si ricevono fino ad esaurimento posti mediante il versamento della quota di partecipazione presso l\u2019agenzia viaggi GerundoTour (Largo&hellip;&nbsp;Leggi tutto &raquo;Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna","og_url":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/","og_site_name":"UNI-Crema","article_published_time":"2024-08-19T17:24:52+00:00","article_modified_time":"2024-09-22T09:34:14+00:00","og_image":[{"width":222,"height":222,"url":"https:\/\/uni-crema.it\/uni-crema\/wp-content\/uploads\/2024\/08\/ligabue-pallavicini-bologna.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/#article","isPartOf":{"@id":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/"},"author":{"name":"admin","@id":"https:\/\/uni-crema.it\/uni-crema\/#\/schema\/person\/cfe1a0a64654788fe56bb76b1ff14816"},"headline":"Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna","datePublished":"2024-08-19T17:24:52+00:00","dateModified":"2024-09-22T09:34:14+00:00","mainEntityOfPage":{"@id":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/"},"wordCount":82,"publisher":{"@id":"https:\/\/uni-crema.it\/uni-crema\/#organization"},"image":{"@id":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/#primaryimage"},"thumbnailUrl":"https:\/\/uni-crema.it\/uni-crema\/wp-content\/uploads\/2024\/08\/ligabue-pallavicini-bologna.jpg","articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/","url":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/","name":"Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna - UNI-Crema","isPartOf":{"@id":"https:\/\/uni-crema.it\/uni-crema\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/#primaryimage"},"image":{"@id":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/#primaryimage"},"thumbnailUrl":"https:\/\/uni-crema.it\/uni-crema\/wp-content\/uploads\/2024\/08\/ligabue-pallavicini-bologna.jpg","datePublished":"2024-08-19T17:24:52+00:00","dateModified":"2024-09-22T09:34:14+00:00","breadcrumb":{"@id":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/#primaryimage","url":"https:\/\/uni-crema.it\/uni-crema\/wp-content\/uploads\/2024\/08\/ligabue-pallavicini-bologna.jpg","contentUrl":"https:\/\/uni-crema.it\/uni-crema\/wp-content\/uploads\/2024\/08\/ligabue-pallavicini-bologna.jpg","width":222,"height":222},{"@type":"BreadcrumbList","@id":"https:\/\/uni-crema.it\/uni-crema\/2024\/08\/19\/ottobre-mostra-di-antonio-ligabue-e-santuario-di-san-luca-a-bologna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uni-crema.it\/uni-crema\/"},{"@type":"ListItem","position":2,"name":"Ottobre: mostra di Antonio Ligabue e santuario di San Luca a Bologna"}]},{"@type":"WebSite","@id":"https:\/\/uni-crema.it\/uni-crema\/#website","url":"https:\/\/uni-crema.it\/uni-crema\/","name":"UNI-Crema","description":"Libera Universit\u00e0 per l&#039;Et\u00e0 Adulta","publisher":{"@id":"https:\/\/uni-crema.it\/uni-crema\/#organization"},"alternateName":"UNI-Crema","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uni-crema.it\/uni-crema\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/uni-crema.it\/uni-crema\/#organization","name":"uni-Crema","alternateName":"Libera Universit\u00e0 per l'Et\u00e0 Adulta","url":"https:\/\/uni-crema.it\/uni-crema\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/uni-crema.it\/uni-crema\/#\/schema\/logo\/image\/","url":"https:\/\/uni-crema.it\/uni-crema\/wp-content\/uploads\/2022\/10\/kigo-UNI-Crema.png","contentUrl":"https:\/\/uni-crema.it\/uni-crema\/wp-content\/uploads\/2022\/10\/kigo-UNI-Crema.png","width":292,"height":234,"caption":"uni-Crema"},"image":{"@id":"https:\/\/uni-crema.it\/uni-crema\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/uni-crema.it\/uni-crema\/#\/schema\/person\/cfe1a0a64654788fe56bb76b1ff14816","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/88214e2decd2e7f1897b7efe07c01fd3e24142626dfbca18f4e479a8adbb6540?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/88214e2decd2e7f1897b7efe07c01fd3e24142626dfbca18f4e479a8adbb6540?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88214e2decd2e7f1897b7efe07c01fd3e24142626dfbca18f4e479a8adbb6540?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/uni-crema.it\/uni-crema"],"url":"https:\/\/uni-crema.it\/uni-crema\/author\/admin\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-27 18:25:24","action":"unstick","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/uni-crema.it\/uni-crema\/wp-json\/wp\/v2\/posts\/10059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uni-crema.it\/uni-crema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uni-crema.it\/uni-crema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uni-crema.it\/uni-crema\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uni-crema.it\/uni-crema\/wp-json\/wp\/v2\/comments?post=10059"}],"version-history":[{"count":3,"href":"https:\/\/uni-crema.it\/uni-crema\/wp-json\/wp\/v2\/posts\/10059\/revisions"}],"predecessor-version":[{"id":10064,"href":"https:\/\/uni-crema.it\/uni-crema\/wp-json\/wp\/v2\/posts\/10059\/revisions\/10064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uni-crema.it\/uni-crema\/wp-json\/wp\/v2\/media\/10061"}],"wp:attachment":[{"href":"https:\/\/uni-crema.it\/uni-crema\/wp-json\/wp\/v2\/media?parent=10059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uni-crema.it\/uni-crema\/wp-json\/wp\/v2\/categories?post=10059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uni-crema.it\/uni-crema\/wp-json\/wp\/v2\/tags?post=10059"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/uni-crema.it\/uni-crema\/wp-json\/wp\/v2\/post_folder?post=10059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}